{"id":8762,"date":"2023-10-15T22:50:00","date_gmt":"2023-10-15T21:50:00","guid":{"rendered":"https:\/\/www.fxbodin.com\/iboga\/?p=8762"},"modified":"2023-11-01T16:54:08","modified_gmt":"2023-11-01T15:54:08","slug":"escapade-a-la-lagune","status":"publish","type":"post","link":"https:\/\/www.fxbodin.com\/iboga\/livre-de-bord\/livre-de-bord-2023-s27\/escapade-a-la-lagune-8762","title":{"rendered":"Escapade \u00e0 la Lagune"},"content":{"rendered":"\n<p>Ce dimanche matin. Beau temps. Je suis pr\u00eat \u00e0 partir avec le descendant \u00e0 09:00. Face au vent d&rsquo;est : GV haute et moteur jusqu&rsquo;\u00e0 la sortie de l&rsquo;estey de Madone. Puis en mode vent arri\u00e8re avec le g\u00e9nois tangonn\u00e9 en ciseaux jusqu&rsquo;\u00e0 Piquey. Ensuite tandis que le ciel se voile, j&#8217;empanne la GV et borde le g\u00e9nois pour me retrouver au pr\u00e8s au bancot (attention la d\u00e9rive !) Je veux traverser les bancs de Bernet le plus au nord pour ne pas me retrouver coinc\u00e9 ensuite.<\/p>\n\n\n\n<p>Pascal sur sa planche \u00e0 voile fait une route plus directe. Car oui, il est parti peu apr\u00e8s moi et a pu couper la dune perdue pour m&rsquo;avoir rattrap\u00e9 d\u00e8s Piquey dans les mouillages.<\/p>\n\n\n\n<p>Alors que l&rsquo;Iboga longe le Pyla, barre amarr\u00e9e, je me fais un caf\u00e9 &#8211; canel\u00e9s-de-la-toque-cuivr\u00e9e-de-Montparnasse (merci Myl\u00e8ne !)<\/p>\n\n\n\n<p>Voil\u00e0 la dune.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.fxbodin.com\/iboga\/files\/Bord-a-bord-babord-amure-cap-sur-la-conche-sud-dArguin-750x563.jpg\" alt=\"\" class=\"wp-image-8769\" srcset=\"https:\/\/www.fxbodin.com\/iboga\/files\/Bord-a-bord-babord-amure-cap-sur-la-conche-sud-dArguin-750x563.jpg 750w, https:\/\/www.fxbodin.com\/iboga\/files\/Bord-a-bord-babord-amure-cap-sur-la-conche-sud-dArguin-450x338.jpg 450w, https:\/\/www.fxbodin.com\/iboga\/files\/Bord-a-bord-babord-amure-cap-sur-la-conche-sud-dArguin-768x576.jpg 768w, https:\/\/www.fxbodin.com\/iboga\/files\/Bord-a-bord-babord-amure-cap-sur-la-conche-sud-dArguin.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption class=\"wp-element-caption\">Bord a\u0300 bord babord amure cap sur la conche sud d&rsquo;Arguin \u2014&nbsp;<a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\">plus de photos<\/a><\/figcaption><\/figure>\n\n\n\n<p>Nous allons arriver peu avant la basse mer. Pas assez d&rsquo;eau pour aller plus loin que derri\u00e8re la langue de sable qui s\u00e9pare la conche du chenal de la \u00ab\u00a0passe sud\u00a0\u00bb. Nous sommes seuls et le resterons pendant toute la mar\u00e9e.<\/p>\n\n\n\n<p>\u00c0 terre, voir l&rsquo;\u00e9tat du banc.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.fxbodin.com\/iboga\/files\/Regardez-la-bien-parce-quelle-ne-ssera-plus-jamais-la-meme-750x563.jpg\" alt=\"\" class=\"wp-image-8770\" srcset=\"https:\/\/www.fxbodin.com\/iboga\/files\/Regardez-la-bien-parce-quelle-ne-ssera-plus-jamais-la-meme-750x563.jpg 750w, https:\/\/www.fxbodin.com\/iboga\/files\/Regardez-la-bien-parce-quelle-ne-ssera-plus-jamais-la-meme-450x338.jpg 450w, https:\/\/www.fxbodin.com\/iboga\/files\/Regardez-la-bien-parce-quelle-ne-ssera-plus-jamais-la-meme-768x576.jpg 768w, https:\/\/www.fxbodin.com\/iboga\/files\/Regardez-la-bien-parce-quelle-ne-ssera-plus-jamais-la-meme.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption class=\"wp-element-caption\">Regardez la bien parce qu&rsquo;elle ne sera plus jamais la m\u00eame ! \u2014 <a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\">d&rsquo;autres photos de moi<\/a><br>\u00ab\u00a0En plein sur Marvel &#x1f44d;\u00a0\u00bb commente <a href=\"https:\/\/www.instagram.com\/p\/Cvuf7Ejqq9w\/?img_index=1\">Scottographe<\/a> sur Insta.<\/figcaption><\/figure>\n\n\n\n<p>Il est \u00e0 peine 13:00 et Paascal s&rsquo;ennuie. Il propose : et si on faisait le tour du banc d&rsquo;Arguin, par le sud, hein ? Ah, ben, pourquoi pas. On mangera plus tard. Seulement voil\u00e0\u00a0: quand je sors de la conche, au lieu de contourner le banc tout de suite, je me dis que je le ferai un peu plus loin. Et puis un peu plus. Et de fil en aiguille, me voil\u00e0 \u00e0 la Lagune, vue directe sur la Salie ! La mar\u00e9e a renvers\u00e9, la houle commence \u00e0 rentrer gros ici. Je fais demi tour. Le jus me propulse \u00e0 7 nds vers le nord (<a href=\"https:\/\/photos.app.goo.gl\/baoiGH1x83tDDvFr9\">preuve<\/a>). Mais il est trop tard pour faire le tour \u00e0 mon avis : la houle d\u00e9ferle d\u00e9j\u00e0 sur les fonds. Je ne connais pas ce passage. On va rester calme.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.fxbodin.com\/iboga\/files\/Le-wharf-en-ligne-de-mire-750x563.jpg\" alt=\"\" class=\"wp-image-8771\" srcset=\"https:\/\/www.fxbodin.com\/iboga\/files\/Le-wharf-en-ligne-de-mire-750x563.jpg 750w, https:\/\/www.fxbodin.com\/iboga\/files\/Le-wharf-en-ligne-de-mire-450x338.jpg 450w, https:\/\/www.fxbodin.com\/iboga\/files\/Le-wharf-en-ligne-de-mire-768x576.jpg 768w, https:\/\/www.fxbodin.com\/iboga\/files\/Le-wharf-en-ligne-de-mire.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption class=\"wp-element-caption\">Le wharf en ligne de mire \u2014 <a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\">toutes les photos<\/a><\/figcaption><\/figure>\n\n\n\n<p>O\u00f9 est Pascal au fait ?<\/p>\n\n\n\n<p>Bah, on se retrouvera bien. Je mets le cap sur le nord, entre banc et dune. Tiens, revoil\u00e0 Pascal. On manque un peu de vent, hein ?<\/p>\n\n\n\n<p>Vers 15:00 j&rsquo;ai pass\u00e9 la pointe nord du banc et fais route \u00e0 travers les d\u00e9ferlantes \u2014 je les connais celles-l\u00e0 \u2014 sur la pointe. Puis Inflexion vers Lavergne. Et le retour habituel le long des parcs du Ferret. Je vais prendre un mouillage dos \u00e0 la c\u00f4te, pour ranger et d\u00e9charger le bateau, avant de le ramener au corps mort et rentrer \u00e0 la nage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"702\" src=\"https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune-750x702.jpg\" alt=\"\" class=\"wp-image-8763\" srcset=\"https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune-750x702.jpg 750w, https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune-450x421.jpg 450w, https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune-768x719.jpg 768w, https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune-1536x1438.jpg 1536w, https:\/\/www.fxbodin.com\/iboga\/files\/15-octobre-2023-Claouey-Arguin-Ferret-sans-lescapade-a-la-Lagune.jpg 1876w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">15 octobre 2023 Claouey &#8211; Arguin &#8211; Ferret sans l&rsquo;escapade a\u0300 la Lagune qui a \u00e9chap\u00e9 \u00e0 mon GPS \u2014&nbsp;<a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\">les photos<\/a><\/figcaption><\/figure>\n\n\n\n<p>Je retrouverai Pascal \u00e0 Claouey o\u00f9 il est rentr\u00e9 directement le long du Moulleau. Belle trotte quand m\u00eame en planche avec ce vent variable \u00e0 incertain&#8230;<\/p>\n\n\n\n<p><a href=\"https:\/\/photos.app.goo.gl\/knepx56JrTCSaKm2A\">Toutes les photos de la mar\u00e9e<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche matin. Beau temps. Je suis pr\u00eat \u00e0 partir avec le descendant \u00e0 09:00. Face au vent d&rsquo;est : GV haute et moteur jusqu&rsquo;\u00e0 la sortie de l&rsquo;estey de Madone. Puis en mode vent arri\u00e8re avec le g\u00e9nois tangonn\u00e9 en ciseaux jusqu&rsquo;\u00e0 Piquey. Ensuite tandis que le ciel se voile, j&#8217;empanne la GV et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1147],"tags":[],"class_list":["post-8762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livre-de-bord-2023-s27"],"_links":{"self":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts\/8762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/comments?post=8762"}],"version-history":[{"count":1,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts\/8762\/revisions"}],"predecessor-version":[{"id":8774,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts\/8762\/revisions\/8774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/media\/8767"}],"wp:attachment":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/media?parent=8762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/categories?post=8762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/tags?post=8762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}