{"id":5494,"date":"2017-08-27T22:14:15","date_gmt":"2017-08-27T21:14:15","guid":{"rendered":"http:\/\/www.fxbodin.com\/iboga\/?p=5494"},"modified":"2017-10-24T11:00:01","modified_gmt":"2017-10-24T10:00:01","slug":"680-connexion-2017","status":"publish","type":"post","link":"https:\/\/www.fxbodin.com\/iboga\/livre-de-bord\/livre-de-bord-2017-s21\/680-connexion-2017-5494","title":{"rendered":"680 Connexion 50-50"},"content":{"rendered":"<p>Attention, chronique en vrac.<br \/>\nCette \u00e9dition, le Champion en Titre avait choisi d&rsquo;apporter son expertise \u00e0 un camarade. Bonaire n&rsquo;\u00e9tait donc pas sur la ligne. La ligne justement : une belle salade de bord\u00e9s \u00e0 la bou\u00e9e au vent !<br \/>\nSuite \u00e0 un d\u00e9part derri\u00e8re toute la flotte, je n&rsquo;ai vu que des tableaux arri\u00e8re jusqu&rsquo;\u00e0 l&rsquo;arriv\u00e9e. Et certains tableaux arri\u00e8res je ne les ai m\u00eame pas vus tellement ils \u00e9taient devant ! \u00c0 l&rsquo;arriv\u00e9e, il y avait <del>3<\/del> 4 bateaux devant l&rsquo;Iboga et 3 derri\u00e8re (dont un solitaire, non inscrit).<br \/>\nEn arri\u00e8re de la flotte, un passage hardi entre bancot et les parcs, tandis que la flotte contournait prudemment le bancot, a permis \u00e0 l&rsquo;Iboga de regagner 2 places qui ne lui furent plus disput\u00e9es.<br \/>\nLa remont\u00e9e du chenal de l&rsquo;\u00eele restera une session de four \u00e0 chaleur tournante o\u00f9 le seul vent \u00e9tait celui produit par le courant ; autant dire que les spis \u00e9taient coll\u00e9s \u00e0 l&rsquo;\u00e9tai ou peu s&rsquo;en faut. Encore heureux que j&rsquo;avais r\u00e9par\u00e9 samedi le tangon de spi, coinc\u00e9 par le sel et oxyde d&rsquo;aluminium depuis deux ans !<br \/>\nCependant, \u00e0 part cet \u00e9pisode, pour une journ\u00e9e annonc\u00e9e p\u00e9tole, il y a eu quand m\u00eame plusieurs s\u00e9quences vent\u00e9es ; suffisamment pour faire marcher nos bateaux. Mapoutchet et le dernier segment de Teychan, dans un petit 3 je dirais, et, toujours dans le d\u00e9sordre, entre le d\u00e9part et la bou\u00e9e 14 avec le courant (merci le Comit\u00e9 pour avoir choisi ce parcours) face \u00e0 un petit 2 bft qui se cherchait au d\u00e9but, on peut naviguer. Le 2 bft qui s&rsquo;est maintenu pour le chenal de Piquey, en faiblissant.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-version=\"7\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:8px;\">\n<div style=\" background:#F8F8F8; line-height:0; margin-top:40px; padding:50.0% 0; text-align:center; width:100%;\">\n<div style=\" background:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAACwAAAAsCAMAAAApWqozAAAABGdBTUEAALGPC\/xhBQAAAAFzUkdCAK7OHOkAAAAMUExURczMzPf399fX1+bm5mzY9AMAAADiSURBVDjLvZXbEsMgCES5\/P8\/t9FuRVCRmU73JWlzosgSIIZURCjo\/ad+EQJJB4Hv8BFt+IDpQoCx1wjOSBFhh2XssxEIYn3ulI\/6MNReE07UIWJEv8UEOWDS88LY97kqyTliJKKtuYBbruAyVh5wOHiXmpi5we58Ek028czwyuQdLKPG1Bkb4NnM+VeAnfHqn1k4+GPT6uGQcvu2h2OVuIf\/gWUFyy8OWEpdyZSa3aVCqpVoVvzZZ2VTnn2wU8qzVjDDetO90GSy9mVLqtgYSy231MxrY6I2gGqjrTY0L8fxCxfCBbhWrsYYAAAAAElFTkSuQmCC); display:block; height:44px; margin:0 auto -44px; position:relative; top:-22px; width:44px;\"><\/div>\n<\/div>\n<p style=\" margin:8px 0 0 0; padding:0 4px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BYTdfDAlloK\/\" style=\" color:#000; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none; word-wrap:break-word;\" target=\"_blank\">Fin de r\u00e9gate sous ciel charg\u00e9 \u00e0 bord de l&#39;Iboga @fxbodin #arcachon #capferret #ileauxoiseaux<\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\">A post shared by Blog du Cap-Ferret (@lecapferret) on <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2017-08-27T16:32:55+00:00\">Aug 27, 2017 at 9:32am PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async defer src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Pour ce qui est de l&rsquo;Iboga, j&rsquo;ai plusieurs excuses, malgr\u00e9 la concentration et l&rsquo;engagement de mon \u00e9quipier Jacques (\u00ab\u00a0&#8230;et c&rsquo;est l\u00e0 qu&rsquo;on ouvre une bi\u00e8re\u00a0\u00bb &#8211; \u00ab\u00a0l\u00e0\u00a0\u00bb c&rsquo;est quand le spi est \u00e9tabli et porte encore), mais je n&rsquo;en ferai pas \u00e9talage<sup id=\"rf1-5494\"><a href=\"#fn1-5494\" title=\"bon, un peu quand m\u00eame : d&rsquo;abord, \u00e7a fait plusieurs saisons que je n&rsquo;ai pas r\u00e9gat\u00e9 \/ pris un d\u00e9part, \u00e7a se perd ; plus, nous ne sommes que 2 \u00e0 bord, c&rsquo;est un peu juste pour enchainer toutes les man\u0153uvres sans \u00e0-coups ; ensuite, une option de route dans les premiers bords qui s&rsquo;est av\u00e9r\u00e9e d\u00e9favorable, j&rsquo;aurais mieux fait de rester dans le lit du courant au lieu de tirer ce bord au nord du chenal ; plus cet \u00e9pisode o\u00f9 je d\u00e9couvre que le mousqueton d&rsquo;amure du g\u00e9nois est \u00e0 moiti\u00e9 d\u00e9croch\u00e9 de la toile, et voil\u00e0 une petite man\u0153uvre sans valeur ajout\u00e9e ; plus la man\u0153uvre d&rsquo;affalage de spi &#8211; renvoi de g\u00e9nois \u00e0 Graou\u00e8res, un peu longue&#8230; bon, le compte y est\" rel=\"footnote\">1<\/a><\/sup>. Ce que je note, c&rsquo;est la Volont\u00e9 d&rsquo;en d\u00e9coudre qui animait une bonne moiti\u00e9 des concurrents et n\u00e9anmoins camarades de Jou\u00ebt. En t\u00e9moignent les optimisations, au ponton avant le briefing : d\u00e9p\u00f4t \u00e0 terre du moteur, changement de voile d&rsquo;avant, passage de brosse sous la coque (bon, moi j&rsquo;avais gratt\u00e9 ma car\u00e8ne au ferret la veille, j&rsquo;avoue ; mais le moteur \u00e0 terre, pas cette fois)&#8230;<br \/>\nVoil\u00e0, quoi dire ?<\/p>\n<p>Lire le classement complet et le vrai compte rendu bien \u00e9crit par le Pdt Jacques Mign\u00e9 de \u00ab\u00a0l&rsquo;Emile Bourgadion\u00a0\u00bb, <a href=\"https:\/\/association.jouet680.free.fr\/activites\/680connexion17.htm\">sur le site de l&rsquo;association des Jou\u00ebt 680<\/a> tenu par Jean-Claude Faucher du \u00ab\u00a0Gaillard\u00a0\u00bb.<\/p>\n<p>La Trace :<br \/>\n[osm_map_v3 map_center=\u00a0\u00bb44.68,-1.191&Prime; zoom=\u00a0\u00bb12&Prime; width=\u00a0\u00bb100%\u00a0\u00bb height=\u00a0\u00bb450&Prime; file_list=\u00a0\u00bb..\/..\/files\/680-Connexion-2017.gpx\u00a0\u00bb type=\u00a0\u00bbOpenSeaMap\u00a0\u00bb control=\u00a0\u00bbfullscreen,scaleline\u00a0\u00bb]\n<p>Cette belle journ\u00e9e sur l&rsquo;eau n&rsquo;aurait pas exist\u00e9 sans le convoyage du samedi soir, essentiellement au moteur, avec la mar\u00e9e montante (pour ne pas risquer la m\u00e9saventure de la 680 Connexion 2010 que je n&rsquo;aurais pas courue <a href=\"https:\/\/www.fxbodin.com\/iboga\/livre-de-bord\/saison_2010\/680-connexion-le-plaisir-et-la-victoire-1786#comment-349028031\">si Vincent et Laurent n&rsquo;\u00e9taient pas venus me tracter<\/a>). Mais l&rsquo;entr\u00e9e dans le port d&rsquo;Arcachon sous voiles, jusqu&rsquo;\u00e0 la cri\u00e9e, pour le principe. Un drop \u00e0 la station essence \u00e0 terre, pour refaire le plein de la nourrice, merci Mathieu. D\u00eener \u00e0 terre.<\/p>\n<p>Et le dimanche matin, r\u00e9veil avec le soleil, dans le port (ah, il est fini le mariage sonoris\u00e9e de cette nuit sur le toit des marchands de jetskis, qu&rsquo;on entendait \u00e0 500m \u00e0 la ronde ?) Th\u00e9 &#8211;<br \/>\n tartines \u00e0 bord. Inscrire le bateau au secr\u00e9tariat du CVA. Je suis le premier je pense. Promenade \u00e0 pieds jusqu&rsquo;au centre ville d&rsquo;Arcachon. D\u00e9j\u00e0 beaucoup de monde. Une vraie r\u00e9ussite cette piste en bois entre le port et Eyrac. Bient\u00f4t <a href=\"https:\/\/www.sauvonslemuseeaquarium.org\/wordpress\/2017\/08\/18\/villa-isly-petit-port-darcachon\/\">un \u00e9norme mur suppl\u00e9mentaire en front de petit port pour h\u00e9berger la Science et le mus\u00e9e Aquarium<\/a>, et \u00e0 la place du <a href=\"https:\/\/www.sauvonslemuseeaquarium.org\/wordpress\/2017\/08\/28\/unephoto-aerienne-de-1968\/\">v\u00e9n\u00e9rable b\u00e2timent du mus\u00e9e<\/a> (fond\u00e9 par la soci\u00e9t\u00e9 scientifique sous la Pr\u00e9sidence d&rsquo;un a\u00efeul Lalesque) s&rsquo;\u00e9rigera une h\u00f4tel consid\u00e9rable, rivalisant de hauteur et de hideur avec le palais des congr\u00e8s qui ench\u00e2sse l&rsquo;\u00e9l\u00e9gant palais Deganne. Mais bon, entre 2 falaises d&rsquo;appartements, de place en place subsistent <a href=\"https:\/\/www.arcachon-nostalgie.com\/villas.htm\">de si jolies villas, certaines modestes, d&rsquo;autres cr\u00e9atives<\/a>. Et leur \u00e9l\u00e9gance ravit les yeux. Bain de foule dans l&rsquo;avenue Thiers car c&rsquo;est Braderie \u00e0 Arcachon. Un point d&rsquo;orgue du Bon Go\u00fbt de cette ancienne station baln\u00e9aire de charme. Le nouveau march\u00e9 est blind\u00e9. Les terrasses aussi. Je vais me r\u00e9fugier en front de mer au Caf\u00e9 de la Plage pour un caf\u00e9-instagram-lecture. <\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-version=\"7\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:8px;\">\n<div style=\" background:#F8F8F8; line-height:0; margin-top:40px; padding:50.0% 0; text-align:center; width:100%;\">\n<div style=\" background:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAACwAAAAsCAMAAAApWqozAAAABGdBTUEAALGPC\/xhBQAAAAFzUkdCAK7OHOkAAAAMUExURczMzPf399fX1+bm5mzY9AMAAADiSURBVDjLvZXbEsMgCES5\/P8\/t9FuRVCRmU73JWlzosgSIIZURCjo\/ad+EQJJB4Hv8BFt+IDpQoCx1wjOSBFhh2XssxEIYn3ulI\/6MNReE07UIWJEv8UEOWDS88LY97kqyTliJKKtuYBbruAyVh5wOHiXmpi5we58Ek028czwyuQdLKPG1Bkb4NnM+VeAnfHqn1k4+GPT6uGQcvu2h2OVuIf\/gWUFyy8OWEpdyZSa3aVCqpVoVvzZZ2VTnn2wU8qzVjDDetO90GSy9mVLqtgYSy231MxrY6I2gGqjrTY0L8fxCxfCBbhWrsYYAAAAAElFTkSuQmCC); display:block; height:44px; margin:0 auto -44px; position:relative; top:-22px; width:44px;\"><\/div>\n<\/div>\n<p style=\" margin:8px 0 0 0; padding:0 4px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BYSpSLclgYp\/\" style=\" color:#000; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none; word-wrap:break-word;\" target=\"_blank\">Arcachon &#8211; \u00e9motions  Int\u00e9ressant d&#39;observer ce que je ressens en parcourant cette ville&#8230;<\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\">A post shared by Fran\u00e7ois-Xavier Bodin (@fxbodin) on <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2017-08-27T08:56:47+00:00\">Aug 27, 2017 at 1:56am PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async defer src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Puis il est l&rsquo;heure de retourner au port pour pr\u00e9parer le bateau et casser la cro\u00fbte en attendant le briefing.<\/p>\n<p>Apr\u00e8s la course, le bateau est \u00e9chou\u00e9 \u00e0 la plage du CVA. Un saut \u00e0 terre pour serrer les mains des vainqueurs. Remercier mon \u00e9quipier qui repart \u00e0 la Teste. Et je profite du vent de S-O 3bft pour tirer un long bord face au courant, \u00e0 2-2,5 nds jusqu&rsquo;\u00e0 devant B\u00e9lisaire.<div id=\"attachment_5521\" style=\"width: 460px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5521\" src=\"https:\/\/www.fxbodin.com\/iboga\/files\/Iboga-lutte-en-vain-contre-le-courant-450x270.jpg\" alt=\"Iboga lutte en vain contre le courant (photo : J\u00e9r\u00f4me)\" width=\"450\" height=\"270\" class=\"size-medium wp-image-5521\" srcset=\"https:\/\/www.fxbodin.com\/iboga\/files\/Iboga-lutte-en-vain-contre-le-courant-450x270.jpg 450w, https:\/\/www.fxbodin.com\/iboga\/files\/Iboga-lutte-en-vain-contre-le-courant-768x461.jpg 768w, https:\/\/www.fxbodin.com\/iboga\/files\/Iboga-lutte-en-vain-contre-le-courant-750x450.jpg 750w, https:\/\/www.fxbodin.com\/iboga\/files\/Iboga-lutte-en-vain-contre-le-courant.jpg 800w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-5521\" class=\"wp-caption-text\">Iboga lutte en vain contre le courant (photo : J\u00e9r\u00f4me)<\/p><\/div> Tentative de battre le courant le long des mouillages, mais le vent faiblit et ce n&rsquo;est pas jouable. Moteur pour finir. Sacr\u00e9 moteur d&rsquo;ailleurs qui d\u00e9marre tr\u00e8s bien et calle tr\u00e8s bien aussi, plus depuis aujourd&rsquo;hui, perd son r\u00e9gime et pousse mal, tout en refroidissant cependant. Et allez, une r\u00e9vision \u00e0 pr\u00e9voir vite&#8230; #maintenance<\/p>\n<p>Ainsi se finit cette s\u00e9quence d&rsquo;un peu plus de 24h de plaisirs.<\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-5494\"><p >bon, un peu quand m\u00eame : d&rsquo;abord, \u00e7a fait plusieurs saisons que je n&rsquo;ai pas r\u00e9gat\u00e9 \/ pris un d\u00e9part, \u00e7a se perd ; plus, nous ne sommes que 2 \u00e0 bord, c&rsquo;est un peu juste pour enchainer toutes les man\u0153uvres sans \u00e0-coups ; ensuite, une option de route dans les premiers bords qui s&rsquo;est av\u00e9r\u00e9e d\u00e9favorable, j&rsquo;aurais mieux fait de rester dans le lit du courant au lieu de tirer ce bord au nord du chenal ; plus cet \u00e9pisode o\u00f9 je d\u00e9couvre que le mousqueton d&rsquo;amure du g\u00e9nois est \u00e0 moiti\u00e9 d\u00e9croch\u00e9 de la toile, et voil\u00e0 une petite man\u0153uvre sans valeur ajout\u00e9e ; plus la man\u0153uvre d&rsquo;affalage de spi &#8211; renvoi de g\u00e9nois \u00e0 Graou\u00e8res, un peu longue&#8230; bon, le compte y est&nbsp;<a href=\"#rf1-5494\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Attention, chronique en vrac. Cette \u00e9dition, le Champion en Titre avait choisi d&rsquo;apporter son expertise \u00e0 un camarade. Bonaire n&rsquo;\u00e9tait donc pas sur la ligne. La ligne justement : une belle salade de bord\u00e9s \u00e0 la bou\u00e9e au vent ! Suite \u00e0 un d\u00e9part derri\u00e8re toute la flotte, je n&rsquo;ai vu que des tableaux arri\u00e8re [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1097],"tags":[52,130,75,805,911],"class_list":["post-5494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livre-de-bord-2017-s21","tag-680-connexion","tag-arcachon","tag-jouet-680","tag-regate","tag-trophee"],"_links":{"self":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts\/5494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/comments?post=5494"}],"version-history":[{"count":0,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/posts\/5494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/media\/5506"}],"wp:attachment":[{"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/media?parent=5494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/categories?post=5494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fxbodin.com\/iboga\/wp-json\/wp\/v2\/tags?post=5494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}